{"id":20698,"date":"2026-03-27T17:37:15","date_gmt":"2026-03-27T20:37:15","guid":{"rendered":"https:\/\/sinprofaz.org.br\/2024\/?p=20698"},"modified":"2026-03-27T17:37:15","modified_gmt":"2026-03-27T20:37:15","slug":"sinprofaz-reforca-os-debates-sobre-inovacao-e-sistema-tributario-no-iat-2026","status":"publish","type":"post","link":"https:\/\/sinprofaz.org.br\/2024\/noticias\/sinprofaz-reforca-os-debates-sobre-inovacao-e-sistema-tributario-no-iat-2026\/","title":{"rendered":"Sinprofaz refor\u00e7a os debates sobre inova\u00e7\u00e3o e sistema tribut\u00e1rio no IAT 2026"},"content":{"rendered":"<p>O Sindicato Nacional dos Procuradores da Fazenda Nacional (Sinprofaz) participou, entre os dias 23 e 25 de mar\u00e7o, do Congresso Internacional de Direito Tribut\u00e1rio do Instituto de Aplica\u00e7\u00e3o do Tributo (IAT), que reuniu especialistas brasileiros e estrangeiros para discutir os rumos da tributa\u00e7\u00e3o. A edi\u00e7\u00e3o teve como presidente de honra o ministro do Supremo Tribunal Federal (STF), Lu\u00eds Roberto Barroso.<\/p>\n<p>Ao longo dos tr\u00eas dias de programa\u00e7\u00e3o, o evento promoveu o di\u00e1logo entre representantes do setor p\u00fablico, da iniciativa privada e da academia em torno de temas centrais como reforma tribut\u00e1ria, transa\u00e7\u00e3o tribut\u00e1ria e moderniza\u00e7\u00e3o da gest\u00e3o fiscal. A programa\u00e7\u00e3o tamb\u00e9m foi marcada pela homenagem \u00e0 Procuradora-Geral da Fazenda Nacional, Anelize Lenzi Ruas de Almeida, reconhecida por sua atua\u00e7\u00e3o \u00e0 frente da PGFN e pelas transforma\u00e7\u00f5es promovidas na rela\u00e7\u00e3o entre o Fisco e os contribuintes.<\/p>\n<p>O Sinprofaz foi representado por meio da sua diretoria e associados. A presidente do sindicato, Val\u00e9ria Ferreira, integrou painel sobre o redesenho federativo, enquanto o diretor de Assuntos Profissionais e Estudos T\u00e9cnicos, Ricardo Almeida Zacharias, debateu os impactos da reforma tribut\u00e1ria no setor de infraestrutura. al\u00e9m disso, Procuradores da Fazenda Nacional tamb\u00e9m contribu\u00edram em diferentes mesas, abordando aspectos t\u00e9cnicos e pr\u00e1ticos da evolu\u00e7\u00e3o do sistema tribut\u00e1rio.<\/p>\n<p>Entre os temas, destacou-se o avan\u00e7o do processo administrativo fiscal digital. Em painel sobre o tema, foram discutidas as possibilidades de uso de big data e de ferramentas tecnol\u00f3gicas para conferir maior racionalidade aos procedimentos. A avalia\u00e7\u00e3o dos participantes foi de que a incorpora\u00e7\u00e3o dessas solu\u00e7\u00f5es pode qualificar a tomada de decis\u00f5es, ampliar a efici\u00eancia administrativa e contribuir para uma rela\u00e7\u00e3o mais equilibrada entre Fisco e contribuintes.<\/p>\n<p>Outros debates abordaram mecanismos de cr\u00e9dito no novo modelo tribut\u00e1rio, alternativas de resolu\u00e7\u00e3o de conflitos e estrat\u00e9gias para aprimorar a gest\u00e3o do contencioso fiscal, refletindo o momento de transi\u00e7\u00e3o vivido pelo sistema brasileiro.<\/p>\n<p>O encerramento do congresso consolidou o evento como um espa\u00e7o relevante de di\u00e1logo t\u00e9cnico e institucional, voltado \u00e0 constru\u00e7\u00e3o de solu\u00e7\u00f5es para os desafios contempor\u00e2neos da tributa\u00e7\u00e3o. A pr\u00f3xima edi\u00e7\u00e3o do Congresso Internacional de Direito Tribut\u00e1rio do IAT acontece em 2027.<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-20698 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-2.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-2-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-3.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-3-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-4.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-4-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-5.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-5-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-6.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-6-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-7.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-7-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-8.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-8-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-9.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-9-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-10.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-10-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-11.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-11-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-12.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-12-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-13.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-13-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-14.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-14-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-15.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-15-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-16.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-16-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-17.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-17-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-18.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-18-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-19.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-19-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Evento reuniu especialistas para discutir os rumos da tributa\u00e7\u00e3o, com participa\u00e7\u00e3o ativa de representantes do Sinprofaz<\/p>\n","protected":false},"author":2,"featured_media":20699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[544,542,543,381,541,540,410,545,44,512,128,135,500,257],"featured_image_url":"https:\/\/sinprofaz.org.br\/2024\/wp-content\/uploads\/2026\/03\/IAT-2026-1.png","character_count":1510,"formatted_date":"27\/03\/2026 - 17:37","contentNovo":"O Sindicato Nacional dos Procuradores da Fazenda Nacional (Sinprofaz) participou, entre os dias 23 e 25 de mar\u00e7o, do Congresso Internacional de Direito Tribut\u00e1rio do Instituto de Aplica\u00e7\u00e3o do Tributo (IAT), que reuniu especialistas brasileiros e estrangeiros para discutir os rumos da tributa\u00e7\u00e3o. A edi\u00e7\u00e3o teve como presidente de honra o ministro do Supremo Tribunal Federal (STF), Lu\u00eds Roberto Barroso.\r\n\r\nAo longo dos tr\u00eas dias de programa\u00e7\u00e3o, o evento promoveu o di\u00e1logo entre representantes do setor p\u00fablico, da iniciativa privada e da academia em torno de temas centrais como reforma tribut\u00e1ria, transa\u00e7\u00e3o tribut\u00e1ria e moderniza\u00e7\u00e3o da gest\u00e3o fiscal. A programa\u00e7\u00e3o tamb\u00e9m foi marcada pela homenagem \u00e0 Procuradora-Geral da Fazenda Nacional, Anelize Lenzi Ruas de Almeida, reconhecida por sua atua\u00e7\u00e3o \u00e0 frente da PGFN e pelas transforma\u00e7\u00f5es promovidas na rela\u00e7\u00e3o entre o Fisco e os contribuintes.\r\n\r\nO Sinprofaz foi representado por meio da sua diretoria e associados. A presidente do sindicato, Val\u00e9ria Ferreira, integrou painel sobre o redesenho federativo, enquanto o diretor de Assuntos Profissionais e Estudos T\u00e9cnicos, Ricardo Almeida Zacharias, debateu os impactos da reforma tribut\u00e1ria no setor de infraestrutura. al\u00e9m disso, Procuradores da Fazenda Nacional tamb\u00e9m contribu\u00edram em diferentes mesas, abordando aspectos t\u00e9cnicos e pr\u00e1ticos da evolu\u00e7\u00e3o do sistema tribut\u00e1rio.\r\n\r\nEntre os temas, destacou-se o avan\u00e7o do processo administrativo fiscal digital. Em painel sobre o tema, foram discutidas as possibilidades de uso de big data e de ferramentas tecnol\u00f3gicas para conferir maior racionalidade aos procedimentos. A avalia\u00e7\u00e3o dos participantes foi de que a incorpora\u00e7\u00e3o dessas solu\u00e7\u00f5es pode qualificar a tomada de decis\u00f5es, ampliar a efici\u00eancia administrativa e contribuir para uma rela\u00e7\u00e3o mais equilibrada entre Fisco e contribuintes.\r\n\r\nOutros debates abordaram mecanismos de cr\u00e9dito no novo modelo tribut\u00e1rio, alternativas de resolu\u00e7\u00e3o de conflitos e estrat\u00e9gias para aprimorar a gest\u00e3o do contencioso fiscal, refletindo o momento de transi\u00e7\u00e3o vivido pelo sistema brasileiro.\r\n\r\nO encerramento do congresso consolidou o evento como um espa\u00e7o relevante de di\u00e1logo t\u00e9cnico e institucional, voltado \u00e0 constru\u00e7\u00e3o de solu\u00e7\u00f5es para os desafios contempor\u00e2neos da tributa\u00e7\u00e3o. A pr\u00f3xima edi\u00e7\u00e3o do Congresso Internacional de Direito Tribut\u00e1rio do IAT acontece em 2027.\r\n\r\n&nbsp;\r\n\r\n[gallery link=\"file\" ids=\"20700,20701,20702,20703,20704,20705,20706,20707,20708,20709,20710,20711,20712,20713,20714,20715,20716,20717\"]","_links":{"self":[{"href":"https:\/\/sinprofaz.org.br\/2024\/wp-json\/wp\/v2\/posts\/20698"}],"collection":[{"href":"https:\/\/sinprofaz.org.br\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sinprofaz.org.br\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sinprofaz.org.br\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sinprofaz.org.br\/2024\/wp-json\/wp\/v2\/comments?post=20698"}],"version-history":[{"count":1,"href":"https:\/\/sinprofaz.org.br\/2024\/wp-json\/wp\/v2\/posts\/20698\/revisions"}],"predecessor-version":[{"id":20718,"href":"https:\/\/sinprofaz.org.br\/2024\/wp-json\/wp\/v2\/posts\/20698\/revisions\/20718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinprofaz.org.br\/2024\/wp-json\/wp\/v2\/media\/20699"}],"wp:attachment":[{"href":"https:\/\/sinprofaz.org.br\/2024\/wp-json\/wp\/v2\/media?parent=20698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sinprofaz.org.br\/2024\/wp-json\/wp\/v2\/categories?post=20698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sinprofaz.org.br\/2024\/wp-json\/wp\/v2\/tags?post=20698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}